{"id":11788,"date":"2018-04-09T10:26:24","date_gmt":"2018-04-09T13:26:24","guid":{"rendered":"http:\/\/www.cidadeemnoticias.com.br\/v1\/?p=11788"},"modified":"2018-04-10T20:12:35","modified_gmt":"2018-04-10T23:12:35","slug":"parada-programada-suspende-abastecimento-em-euclides-da-cunha-cansancao-monte-santo-quijingue-e-nordestina-nesta-terca-feira","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2018\/04\/09\/parada-programada-suspende-abastecimento-em-euclides-da-cunha-cansancao-monte-santo-quijingue-e-nordestina-nesta-terca-feira\/","title":{"rendered":"Parada programada suspende abastecimento em Euclides da Cunha, Cansan\u00e7\u00e3o, Monte Santo, Quijingue e Nordestina nesta ter\u00e7a-feira"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\" wp-image-891 aligncenter\" src=\"http:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2016\/12\/EMBASA-300x200.jpg\" alt=\"embasa\" width=\"452\" height=\"301\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2016\/12\/EMBASA-300x200.jpg 300w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2016\/12\/EMBASA-768x512.jpg 768w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2016\/12\/EMBASA-1024x683.jpg 1024w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/><\/h3>\n<h3 style=\"text-align: justify;\">uma adutora no Sistema de Tucano I. A medida causar\u00e1 a interrup\u00e7\u00e3o tempor\u00e1ria do fornecimento de \u00e1gua nos munic\u00edpios de Euclides da Cunha, Cansan\u00e7\u00e3o, Monte Santo, Quijingue e Nordestina a partir das 08h.<\/h3>\n<h3 style=\"text-align: justify;\">A previs\u00e3o \u00e9 de que a conclus\u00e3o dos servi\u00e7os ocorra \u00e0s 12h. do dia seguinte (11), possibilitando a retomada gradativa do abastecimento de \u00e1gua nas localidades afetadas. Para evitar maiores transtornos, a Embasa recomenda aos moradores que fa\u00e7am reserva\u00e7\u00e3o adequada e reduzam o consumo da \u00e1gua durante este per\u00edodo.<\/h3>\n<h3 style=\"text-align: justify;\">\u00a0Assessoria de Comunica\u00e7\u00e3o da Embasa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>uma adutora no Sistema de Tucano I. A medida causar\u00e1 a interrup\u00e7\u00e3o tempor\u00e1ria do fornecimento de \u00e1gua nos munic\u00edpios de Euclides da Cunha, Cansan\u00e7\u00e3o, Monte Santo, Quijingue e Nordestina a partir das 08h. A previs\u00e3o \u00e9 de que a conclus\u00e3o dos servi\u00e7os ocorra \u00e0s 12h. do dia seguinte (11), possibilitando a retomada gradativa do abastecimento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/11788"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=11788"}],"version-history":[{"count":2,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/11788\/revisions"}],"predecessor-version":[{"id":11794,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/11788\/revisions\/11794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/891"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=11788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=11788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=11788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}