{"id":11904,"date":"2018-04-13T08:12:12","date_gmt":"2018-04-13T11:12:12","guid":{"rendered":"http:\/\/www.cidadeemnoticias.com.br\/v1\/?p=11904"},"modified":"2018-04-13T08:14:37","modified_gmt":"2018-04-13T11:14:37","slug":"empresa-inicia-obras-de-construcao-da-policlinica-regional-de-senhor-do-bonfim","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2018\/04\/13\/empresa-inicia-obras-de-construcao-da-policlinica-regional-de-senhor-do-bonfim\/","title":{"rendered":"Empresa inicia obras de constru\u00e7\u00e3o da Policl\u00ednica Regional de Senhor do Bonfim"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\" wp-image-11905 aligncenter\" src=\"http:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2018\/04\/774398e0-a418-4768-a0c2-1bee85ad7493-300x169.jpg\" alt=\"774398e0-a418-4768-a0c2-1bee85ad7493\" width=\"412\" height=\"232\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2018\/04\/774398e0-a418-4768-a0c2-1bee85ad7493-300x169.jpg 300w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2018\/04\/774398e0-a418-4768-a0c2-1bee85ad7493.jpg 600w\" sizes=\"(max-width: 412px) 100vw, 412px\" \/><\/h3>\n<h3 style=\"text-align: justify;\">Axxo Construtora Ltda iniciou na quarta-feira, 11, as obras de constru\u00e7\u00e3o da Policl\u00ednica Regional de Sa\u00fade de Senhor do Bonfim.<\/h3>\n<h3 style=\"text-align: justify;\">A policl\u00ednica est\u00e1 sendo instalada nas margens da rodovia que liga os munic\u00edpios de Senhor do Bonfim a Campo Formoso(BA-220), por tr\u00e1s Gin\u00e1sio de Esportes Paulo Braga (no bairro grande Olaria).<\/h3>\n<h3 style=\"text-align: justify;\">O investimento para erguer a policl\u00ednica \u00e9 de cerca de R$ 11 milh\u00f5es, o valor inclui somente a parte estrutural. O investimento total ser\u00e1 de aproximadamente R$ 25 milh\u00f5es \u2013 os recursos s\u00e3o do governo do estado da Bahia.<\/h3>\n<h3 style=\"text-align: justify;\"><em>\u201cO prefeito Carlos Brasileiro nos delegou juntamente com o secret\u00e1rio Benito Brasileiro (Planejamento e Finan\u00e7as), que recebesse o pessoal da Axxo Engenharia, para facilitar tudo que for necess\u00e1rio para come\u00e7ar efetivamente essa grande obra que vai beneficiar o povo de Senhor do Bonfim, e de todas as cidades que fazem parte do Cons\u00f3rcio de Sa\u00fade\u201d<\/em>, enfatizou o vice-prefeito Jos\u00e9 Ant\u00f4nio.<\/h3>\n<h3 style=\"text-align: justify;\">A \u00e1rea constru\u00edda ser\u00e1 de 4 mil metros quadrados, e quando estiver constru\u00edda, a popula\u00e7\u00e3o dos munic\u00edpios participantes ter\u00e1 acesso a consultas especializadas gratuitas com m\u00e9dicos Angiologistas, Cardiologistas, Endocrinologistas, Mastologistas, Neurologistas, Otorrinolaringologistas, Oftalmologistas, Urologistas, Cl\u00ednicos, Gastroenterologistas, Ginecologistas e Obstetras,Traumatologistas -ortopedistas, e Cirurgi\u00f5es Gerais.<\/h3>\n<h3 style=\"text-align: justify;\">Tamb\u00e9m ser\u00e3o oferecidos \u00e0 popula\u00e7\u00e3o, de forma gratuita, exames de m\u00e9dia e alta complexidade, como Resson\u00e2ncias Magn\u00e9ticas, Tomografias Computadorizadas, Mapas, Ecocardiogramas, Eletrocardiogramas, Eletroencefalogramas, Endoscopia Digestiva e Respirat\u00f3ria, Ultrassonografias, Radiografias, Audiometrias, ECG, Mamografias, Testes Ergom\u00e9tricos, e Bi\u00f3psias.<\/h3>\n<h3 style=\"text-align: justify;\"><em>\u201cN\u00f3s acreditamos que a policl\u00ednica vai contribuir muito para o desenvolvimento da nossa cidade e, principalmente, para melhorar os problemas da sa\u00fade na nossa regi\u00e3o\u201d<\/em>, disse o secret\u00e1rio Benito Brasileiro.<\/h3>\n<h3 style=\"text-align: justify;\">A obra est\u00e1 iniciando com o servi\u00e7o de demarca\u00e7\u00e3o topogr\u00e1fica e nivelamento (terraplanagem) do espa\u00e7o. Conforme a empresa respons\u00e1vel, o prazo m\u00e1ximo para finaliza\u00e7\u00e3o ser\u00e1 de 12 meses.<\/h3>\n<h3 style=\"text-align: justify;\"><em>\u201cA constru\u00e7\u00e3o ser\u00e1 toda em concreto, e na frente, tem uma estrutura \u201cespacial\u201d com vidro que vai embelezar muito a fachada da obra\u201d,<\/em>\u00a0disse o engenheiro da Axxo ,Orlando Lemos.<\/h3>\n<h3 style=\"text-align: justify;\">\u201cA entrega em contrato \u00e9 para o m\u00eas de abril de 2019, mas pretendemos antecipar esse prazo\u201d, salientou Orlando.<\/h3>\n<h3 style=\"text-align: justify;\">O estado se responsabiliza pela constru\u00e7\u00e3o e aquisi\u00e7\u00e3o dos equipamentos das unidades, al\u00e9m de financiar at\u00e9 40% da manuten\u00e7\u00e3o, enquanto os munic\u00edpios consorciados rateiam os 60% restantes. O Governador Rui Costa estar\u00e1 em Senhor do Bonfim na sexta (27) para assinar ordem de servi\u00e7os da Policl\u00ednica.<\/h3>\n<h3 style=\"text-align: justify;\">ASCOM \u2013 Prefeitura Municipal de Senhor do Bonfim\/Blog do Netto<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Axxo Construtora Ltda iniciou na quarta-feira, 11, as obras de constru\u00e7\u00e3o da Policl\u00ednica Regional de Sa\u00fade de Senhor do Bonfim. A policl\u00ednica est\u00e1 sendo instalada nas margens da rodovia que liga os munic\u00edpios de Senhor do Bonfim a Campo Formoso(BA-220), por tr\u00e1s Gin\u00e1sio de Esportes Paulo Braga (no bairro grande Olaria). O investimento para erguer [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/11904"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=11904"}],"version-history":[{"count":1,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/11904\/revisions"}],"predecessor-version":[{"id":11906,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/11904\/revisions\/11906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/11905"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=11904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=11904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=11904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}