{"id":12267,"date":"2018-05-08T15:36:22","date_gmt":"2018-05-08T18:36:22","guid":{"rendered":"http:\/\/www.cidadeemnoticias.com.br\/v1\/?p=12267"},"modified":"2018-05-08T16:31:00","modified_gmt":"2018-05-08T19:31:00","slug":"enem-2018-inscricoes-estao-abertas","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2018\/05\/08\/enem-2018-inscricoes-estao-abertas\/","title":{"rendered":"Enem 2018: Inscri\u00e7\u00f5es est\u00e3o abertas"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"wp-image-12268 aligncenter\" src=\"http:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2018\/05\/enem-2018-300x244.jpg\" alt=\"enem-2018\" width=\"384\" height=\"312\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2018\/05\/enem-2018-300x244.jpg 300w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2018\/05\/enem-2018.jpg 695w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/h3>\n<h3 style=\"text-align: justify;\">As inscri\u00e7\u00f5es para o Exame Nacional do Ensino M\u00e9dio (Enem) 2018 foram abertas\u00a0<strong><a href=\"https:\/\/enem.inep.gov.br\/participante\/#!\/loginInscricao\" target=\"_blank\">no site<\/a><\/strong>\u00a0nesta segunda-feira (7) e ir\u00e3o at\u00e9 o dia 18 de maio, \u00e0s 23h59, segundo o manual do candidato. Todos os interessados em participar da prova devem faz\u00ea-la, inclusive aqueles que conseguiram a isen\u00e7\u00e3o da taxa de R$ 82. A\u00a0aprova\u00e7\u00e3o do pedido de isen\u00e7\u00e3o, que foi feito em um per\u00edodo anterior, n\u00e3o significa estar inscrito no exame.<\/h3>\n<h3 class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\">No caso dos estudantes que ter\u00e3o de pagar esse valor para se inscrever, o prazo m\u00e1ximo para quitar o boleto banc\u00e1rio \u00e9 o dia 23 de maio. Mesmo que haja um feriado regional e os bancos n\u00e3o funcionem, a data-limite n\u00e3o ser\u00e1 alterada, segundo o Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep).<\/h3>\n<h3 class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\">Para fazer a inscri\u00e7\u00e3o, \u00e9 necess\u00e1rio informar o n\u00famero do CPF e do RG para que seja criada uma senha. \u00c9 ela que dar\u00e1 acesso futuramente ao cart\u00e3o de confirma\u00e7\u00e3o e aos resultados, por exemplo. Tamb\u00e9m \u00e9 preciso ter um n\u00famero de celular e um e-mail v\u00e1lidos, para que o Inep envie comunicados diretamente aos candidatos.<\/h3>\n<h3 class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\">Al\u00e9m desses dados, os estudantes t\u00eam de afirmar se necessitam de algum atendimento especializado no dia da prova (como para pessoas com defici\u00eancia ou lactantes). Em outra etapa da inscri\u00e7\u00e3o, precisam marcar se a l\u00edngua estrangeira cobrada na prova ser\u00e1 o ingl\u00eas ou o espanhol.<\/h3>\n<h3 style=\"text-align: justify;\">O Enem seleciona candidatos para o Sisu, Prouni, Fies e universidades portuguesas.<\/h3>\n<p><strong>Datas das provas<\/strong><\/p>\n<h3 class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\">O Enem acontecer\u00e1 em dois domingos, nos dias 4 e 11 de novembro:<\/h3>\n<ul class=\"content-unordered-list\" style=\"text-align: justify;\">\n<li>\n<h3>04\/11: 45 quest\u00f5es de linguagens, 45 de ci\u00eancias humanas e reda\u00e7\u00e3o.<\/h3>\n<\/li>\n<\/ul>\n<h3 class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\">Dura\u00e7\u00e3o: 5h30<\/h3>\n<ul class=\"content-unordered-list\" style=\"text-align: justify;\">\n<li>\n<h3>11\/11: 45 quest\u00f5es de ci\u00eancias da natureza e 45 de matem\u00e1tica.<\/h3>\n<\/li>\n<\/ul>\n<h3 class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\">Dura\u00e7\u00e3o: 5h (30 minutos a mais do que em 2017)<\/h3>\n<p><strong>Hor\u00e1rios das provas<\/strong><\/p>\n<div data-track-category=\"fim do conteudo\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"entrada completa viewport\">\n<ul class=\"content-unordered-list\" style=\"text-align: justify;\">\n<li>\n<h3>Abertura dos port\u00f5es: 12h<\/h3>\n<\/li>\n<li>\n<h3>Fechamento dos port\u00f5es: 13h<\/h3>\n<\/li>\n<li>\n<h3>In\u00edcio das provas: 13h30<\/h3>\n<\/li>\n<li>\n<h3>Encerramento das provas: 19h (primeiro dia) e 18h30 (segundo dia)<\/h3>\n<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">Not\u00edcias de Santaluz<\/h3>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As inscri\u00e7\u00f5es para o Exame Nacional do Ensino M\u00e9dio (Enem) 2018 foram abertas\u00a0no site\u00a0nesta segunda-feira (7) e ir\u00e3o at\u00e9 o dia 18 de maio, \u00e0s 23h59, segundo o manual do candidato. Todos os interessados em participar da prova devem faz\u00ea-la, inclusive aqueles que conseguiram a isen\u00e7\u00e3o da taxa de R$ 82. A\u00a0aprova\u00e7\u00e3o do pedido de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/12267"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=12267"}],"version-history":[{"count":2,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/12267\/revisions"}],"predecessor-version":[{"id":12277,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/12267\/revisions\/12277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/12268"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=12267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=12267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=12267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}