{"id":20588,"date":"2021-02-20T11:40:57","date_gmt":"2021-02-20T14:40:57","guid":{"rendered":"https:\/\/www.cidadeemnoticias.com.br\/v1\/?p=20588"},"modified":"2021-02-21T11:38:47","modified_gmt":"2021-02-21T14:38:47","slug":"itiuba-fica-deserta-apos-a-1a-noite-do-toque-de-recolher","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2021\/02\/20\/itiuba-fica-deserta-apos-a-1a-noite-do-toque-de-recolher\/","title":{"rendered":"ITI\u00daBA FICA DESERTA AP\u00d3S A 1\u00aa NOITE DO TOQUE DE RECOLHER"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-20594 aligncenter\" src=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-19-at-22.14.10-1-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-19-at-22.14.10-1-300x225.jpeg 300w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-19-at-22.14.10-1.jpeg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3 style=\"text-align: justify;\">As ruas de Iti\u00faba ficaram vazias em plena noite de sexta &#8211; feira, 19 de fevereiro de 2021, ap\u00f3s o inicio do Toque de Recolher, \u00e0s 22 horas.<\/h3>\n<h3 style=\"text-align: justify;\">Mesmo com o baixo n\u00famero de casos ativos e um decreto municipal que autorizou a abertura de bares e restaurantes, o munic\u00edpio tamb\u00e9m teve que aderir ao decreto Estadual que entrou em vigor nesta sexta &#8211; feira.<\/h3>\n<h3 style=\"text-align: justify;\">Segundo o Governador Rui Costa, a medida foi tomada ap\u00f3s\u00a0 a ocupa\u00e7\u00e3o em 77% do n\u00famero de leitos de UTIs no Estado e tem por objetivo conter o aumento de casos e mortes pelo Covid &#8211; 19. O Decreto \u00e9 valido at\u00e9 o dia 25 de fevereiro.<\/h3>\n<p>Cidade em Not\u00edcias<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As ruas de Iti\u00faba ficaram vazias em plena noite de sexta &#8211; feira, 19 de fevereiro de 2021, ap\u00f3s o inicio do Toque de Recolher, \u00e0s 22 horas. Mesmo com o baixo n\u00famero de casos ativos e um decreto municipal que autorizou a abertura de bares e restaurantes, o munic\u00edpio tamb\u00e9m teve que aderir ao [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,26],"tags":[33,35,36,34,46,62,39,68,40,37],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/20588"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=20588"}],"version-history":[{"count":3,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/20588\/revisions"}],"predecessor-version":[{"id":20596,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/20588\/revisions\/20596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/20594"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=20588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=20588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=20588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}