{"id":21228,"date":"2021-04-11T14:36:20","date_gmt":"2021-04-11T17:36:20","guid":{"rendered":"https:\/\/www.cidadeemnoticias.com.br\/v1\/?p=21228"},"modified":"2021-04-11T16:49:55","modified_gmt":"2021-04-11T19:49:55","slug":"a-seguranca-juridica-e-o-relativo-poder-do-administrador-conferido-pela-sumula-473-parte-iv","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2021\/04\/11\/a-seguranca-juridica-e-o-relativo-poder-do-administrador-conferido-pela-sumula-473-parte-iv\/","title":{"rendered":"A SEGURAN\u00c7A JUR\u00cdDICA e o relativo poder do administrador conferido pela S\u00famula 473, PARTE IV"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-21229 aligncenter\" src=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-01-11-at-20.30.45-200x300.jpeg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-01-11-at-20.30.45-200x300.jpeg 200w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-01-11-at-20.30.45-682x1024.jpeg 682w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-01-11-at-20.30.45-768x1152.jpeg 768w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-01-11-at-20.30.45.jpeg 853w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<h3 style=\"font-weight: 400; text-align: justify;\">Muitos gestores t\u00eam utilizado a S\u00famula 473, do STF (Supremo Tribunal Federal) para agir desrespeitando os princ\u00edpios do SDIREITO ADQUIRIDO e da DIGNIDADE DA PESSOA HUMANA, porque o verbete estabelece em forma de ac\u00f3rd\u00e3o, que a qualquer tempo a Administra\u00e7\u00e3o P\u00fablica pode rever os seus atos praticados com v\u00edcios de legalidade, firmando, assim, o entendimento de que n\u00e3o h\u00e1 prazo para a anula\u00e7\u00e3o de atos praticados em qualquer tempo, independentemente do tempo transcorrido e do aproveitamento que foi obtido em favor da Administra\u00e7\u00e3o, em preju\u00edzo do cidad\u00e3o que serve port anos a fio, sem que a Administra\u00e7\u00e3o P\u00fablica corrija o seu erro.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Diz a S\u00famula 473, do STF:<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\"><strong><em>\u201cA administra\u00e7\u00e3o pode anular seus pr\u00f3prios atos, quando eivados de v\u00edcios que os tornam ilegais, porque deles n\u00e3o se originam direitos; ou revog\u00e1-los, por motivo de conveni\u00eancia ou oportunidade, RESPEITADOS OS DIREITOS ADQUIRIDOS, e ressalvada, em todos os casos, a aprecia\u00e7\u00e3o judicial\u201d.\u00a0<\/em><\/strong>(Destaquei em mai\u00fasculas).<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">No entanto, no julgamento do Recurso Extraordin\u00e1rio n\u00ba 594.296, que teve o Ministro Dias Tofolli como relator, ficou definida a seguinte tese de Repercuss\u00e3o Geral, conforme publica\u00e7\u00e3o do Tema 138, no Di\u00e1rio da Justi\u00e7a-Eletr\u00f4nico, de 13-2-2012, portanto, cerca de 24 (vinte e quatro) anos depois da promulga\u00e7\u00e3o da nova Constitui\u00e7\u00e3o e 43 (quarenta e tr\u00eas )anos ap\u00f3s entrada em vigor do enunciado da S\u00famula 473 do STF, ocorrido em 10-12~1969, sob o regi,e militar, 19 (dezenove anos antes da nossa atual Constitui\u00e7\u00e3o.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Leiamos:<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\"><em><strong>\u00a0\u201cAo Estado \u00e9 facultada a revoga\u00e7\u00e3o de atos que repute ilegalmente praticados; por\u00e9m, se de tais atos j\u00e1 tiverem decorrido efeitos concretos, seu desfazimento deve ser precedido de regular processo administrativo\u201d.\u00a0<\/strong><\/em><em><strong>[Tese definida no\u00a0<\/strong><\/em><strong><em><a href=\"http:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=TP&amp;docID=1729772\">RE 594.296<\/a><\/em><\/strong><em><strong>, rel. min.\u00a0<\/strong><\/em><strong><em>Dias Toffoli<\/em><\/strong><em><strong>, P, j. 21-9-2011,\u00a0<\/strong><\/em><strong><em>DJE\u00a0<\/em><\/strong><em><strong>146 de 13-2-2012,\u00a0<a href=\"http:\/\/www.stf.jus.br\/portal\/jurisprudenciaRepercussao\/verAndamentoProcesso.asp?incidente=2644122&amp;numeroProcesso=594296&amp;classeProcesso=RE&amp;numeroTema=138\">Tema 138.<\/a>].<\/strong><\/em><\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\"><em>Nesse julgamento, o Min. Dias Toffoli teve o cuidado de explicitar com clareza a sua posi\u00e7\u00e3o, expressando no seu voto com o seguinte entendimento:<\/em><\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\"><strong><em>\u201cO recorrente pretendeu ver reconhecida a legalidade de seu agir, com respaldo no verbete da S\u00famula 473 desta Suprema Corte, editada ainda no ano de 1969. Sob a \u00e9gide, portanto, da Constitui\u00e7\u00e3o anterior, (&#8230;). A partir da promulga\u00e7\u00e3o da Constitui\u00e7\u00e3o Federal de 1988, foi erigido \u00e0 condi\u00e7\u00e3o de garantia constitucional do cidad\u00e3o, quer se encontre na posi\u00e7\u00e3o de litigante, num processo judicial, que seja um mero interessado, em um processo administrativo, o direito ao contradit\u00f3rio e \u00e0 ampla defesa, com os meios e recursos a eles inerentes. Ou seja, a partir de ent\u00e3o, qualquer ato da Administra\u00e7\u00e3o P\u00fablica que tiver o cond\u00e3o de repercutir sobre a esfera de interesse do cidad\u00e3o dever\u00e1 ser precedido de pr\u00e9vio procedimento em que\u00a0\u00a0se assegure ao interessado o efetivo exerc\u00edcio do direito ao contradit\u00f3rio e \u00e0 ampla defesa. Mostra-se, ent\u00e3o, necess\u00e1rio, proceder-se \u00e0 compatibiliza\u00e7\u00e3o entre o comando exarado pela aludida s\u00famula e o direito ao exerc\u00edcio pleno do contradit\u00f3rio e da ampla defesa, garantidos ao cidad\u00e3o pela norma do art. 5\u00ba, inciso LV, de nossa Constitui\u00e7\u00e3o Federal\u201d.\u00a0<\/em><\/strong>[<strong><a href=\"http:\/\/www.stf.jus.br\/portal\/inteiroTeor\/obterInteiroTeor.asp?idDocumento=1729772\">RE 594.296<\/a><\/strong>, rel. min.\u00a0<strong>Dias Toffoli<\/strong>, P, j. 21-9-2011,\u00a0<em>DJE<\/em>\u00a0146 de 13-2-2012,\u00a0<a href=\"http:\/\/www.stf.jus.br\/portal\/jurisprudenciaRepercussao\/verAndamentoProcesso.asp?incidente=2644122&amp;numeroProcesso=594296&amp;classeProcesso=RE&amp;numeroTema=138\">Tema 138<\/a>.]<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Coinveniente, portanto, reproduzir o inciso LV, do artigo 5\u00ba, da atuasl Constitui\u00e7\u00e3o Federal, como segue:<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\"><strong><em>\u201cAos litigantes, em processo judicial ou administrativo, e aos acusados em geral s\u00e3o assegurados o contradit\u00f3rio e ampla defesa, com os meios e recursos a ela inerentes\u201d<\/em><\/strong><\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Evidentemente que a vetusta S\u00famula n.\u00ba 473 do STF, reconheceu na autotutela administrativa inclusive o poder de anular seus atos quando eivados de nulidade, porque deles n\u00e3o se originam direitos, vem a contrapor-se a este entendimento. H\u00e1 que se sopesar, contudo, teleologicamente, o contexto em que se produziu tal s\u00famula (editada em 3.10.1969, plena ditadura militar) com a novel dogm\u00e1tica jurisconstitucional garantidora de direitos e afirmativos do indiv\u00edduo, na esteira da Constitui\u00e7\u00e3o Cidad\u00e3 de 1988.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">No entender do insigne\u00a0<strong>Min. do STF (quando ocupava cadeira no STJ), LUIZ FUX<\/strong>:\u00a0<strong><em>\u201cSe \u00e9 assente que a Administra\u00e7\u00e3o pode cancelar seus atos, tamb\u00e9m o \u00e9 que por for\u00e7a do princ\u00edpio da seguran\u00e7a jur\u00eddica obedece aos direitos adquiridos e reembolsa eventuais preju\u00edzos pelos seus atos il\u00edcitos ou originariamente l\u00edcitos, como consect\u00e1rio do controle jurisdicional e das responsabilidades dos atos da Administra\u00e7\u00e3o. (&#8230;) Em consequ\u00eancia, n\u00e3o \u00e9 absoluto o poder do administrador, conforme insinua a S\u00famula 473\u201d<\/em><\/strong>\u00a0<strong>(STJ, REsp. n.\u00ba 402.638\/DF, j. 03.04.03, pub. DJU 02.06.03, p.187; RDDP, vol. N.\u00ba 5, p.237).<\/strong><\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Ainda na jurisprud\u00eancia do STJ, \u00e9 supinamente salutar \u00e0 compreens\u00e3o do texto ter-se em mente um excerto de voto da Exma. Min.\u00a0<strong>LAURITA VAZ:<\/strong>\u00a0<strong><em>\u201cN\u00e3o pode o administrado ficar sujeito indefinidamente ao poder de autotutela do Estado, sob pena de desestabilizar um dos pilares mestres do estado democr\u00e1tico de direito, qual seja, o princ\u00edpio da seguran\u00e7a das rela\u00e7\u00f5es jur\u00eddicas\u201d<\/em><\/strong>\u00a0<strong>(STJ, REsp n.\u00ba 645856\/RS, j. 24.08.04, pub. DJU 13.09.04, p.291).<\/strong><\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Percebe-se, claramente, que o Poder de Autotulela Administrativa conferida aos gestores p\u00fablicos pela S\u00famula 473, do STF, n\u00e3o \u00e9 absoluto, como querem aqueles que desrespeitam o DIRFEITO ADQUIRIDO e o PRINC\u00cdPIO DA SEGURAN\u00c7A DAS RELA\u00c7\u00d5ES JUR\u00cdDICAS, impondo, pois, plena relativiza\u00e7\u00e3o, porque o verbete sumular citado est\u00e1 submisso a princ\u00edpios garantidores dos direitos fundamentais do cidad\u00e3o.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Na\u00a0<u>PARTE V<\/u>, a abordagem ser\u00e1 sobre\u00a0<u>A SEGURAN\u00c7A JUR\u00cdDICA e sua rela\u00e7\u00e3o com a boa-f\u00e9.<\/u><\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\"><strong>*Josemar Santana \u00e9 jornalista e advogado, especializado em Direito P\u00fablico, Direito Eleitoral, Direito Criminal, Procuradoria Jur\u00eddica, integrante do Escrit\u00f3rio Santana Advocacia, com unidades em Senhor do Bonfim (Ba) e Salvador (Ba). Site: www.santanaadv.com \/ E-mail: josemarsantana@santanaadv.com<\/strong><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Muitos gestores t\u00eam utilizado a S\u00famula 473, do STF (Supremo Tribunal Federal) para agir desrespeitando os princ\u00edpios do SDIREITO ADQUIRIDO e da DIGNIDADE DA PESSOA HUMANA, porque o verbete estabelece em forma de ac\u00f3rd\u00e3o, que a qualquer tempo a Administra\u00e7\u00e3o P\u00fablica pode rever os seus atos praticados com v\u00edcios de legalidade, firmando, assim, o entendimento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":21229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[2,25],"tags":[243,184,244,242],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/21228"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=21228"}],"version-history":[{"count":1,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/21228\/revisions"}],"predecessor-version":[{"id":21230,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/21228\/revisions\/21230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/21229"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=21228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=21228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=21228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}