{"id":22827,"date":"2021-11-23T20:04:11","date_gmt":"2021-11-23T23:04:11","guid":{"rendered":"https:\/\/www.cidadeemnoticias.com.br\/v1\/?p=22827"},"modified":"2021-11-27T11:44:27","modified_gmt":"2021-11-27T14:44:27","slug":"vereador-ivan-da-saude-e-eleito-1o-secretario-da-mesa-diretora-da-camara-de-vereadores-de-itiuba","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2021\/11\/23\/vereador-ivan-da-saude-e-eleito-1o-secretario-da-mesa-diretora-da-camara-de-vereadores-de-itiuba\/","title":{"rendered":"VEREADOR IVAN DA SA\u00daDE \u00c9 ELEITO 1\u00ba SECRET\u00c1RIO DA MESA DIRETORA DA C\u00c2MARA DE VEREADORES DE ITI\u00daBA"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-22828 aligncenter\" src=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-23-at-19.50.47-242x300.jpeg\" alt=\"\" width=\"242\" height=\"300\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-23-at-19.50.47-242x300.jpeg 242w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-23-at-19.50.47-827x1024.jpeg 827w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-23-at-19.50.47-768x951.jpeg 768w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-23-at-19.50.47.jpeg 1034w\" sizes=\"(max-width: 242px) 100vw, 242px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Aconteceu na noite desta ter\u00e7a &#8211; feira, 23 de novembro de 2021, a Sess\u00e3o Extraordin\u00e1ria para a escolha do Novo 1\u00ba Secret\u00e1rio da C\u00e2mara de Vereadores de Iti\u00faba.<\/h3>\n<h3 style=\"text-align: justify;\">Foi eleito por unanimidade, o Vereador Ivan da Sa\u00fade do PCdoB, que j\u00e1 tomou posse do cargo e iniciou na sess\u00e3o seguinte seus trabalhos. A escolha do Edil foi necess\u00e1ria devido a ren\u00fancia do ent\u00e3o Secret\u00e1rio da Mesa, Edson Laranjeira que ficou frente aos trabalhos por 10 meses.<\/h3>\n<h3 style=\"text-align: justify;\">A causa da renuncia de Edson nunca ficou clara, por\u00e9m rumores deram conta de diverg\u00eancias entre o Secret\u00e1rio da Casa e o Presidente, mas os edis n\u00e3o confirmaram essa informa\u00e7\u00e3o.<\/h3>\n<p>Cidade em Not\u00edcias<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aconteceu na noite desta ter\u00e7a &#8211; feira, 23 de novembro de 2021, a Sess\u00e3o Extraordin\u00e1ria para a escolha do Novo 1\u00ba Secret\u00e1rio da C\u00e2mara de Vereadores de Iti\u00faba. Foi eleito por unanimidade, o Vereador Ivan da Sa\u00fade do PCdoB, que j\u00e1 tomou posse do cargo e iniciou na sess\u00e3o seguinte seus trabalhos. A escolha do [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3,26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/22827"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=22827"}],"version-history":[{"count":4,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/22827\/revisions"}],"predecessor-version":[{"id":22832,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/22827\/revisions\/22832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/22828"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=22827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=22827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=22827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}