{"id":26305,"date":"2023-04-16T17:53:12","date_gmt":"2023-04-16T20:53:12","guid":{"rendered":"https:\/\/www.cidadeemnoticias.com.br\/v1\/?p=26305"},"modified":"2023-04-16T17:54:34","modified_gmt":"2023-04-16T20:54:34","slug":"ver-todas-de-colunistas-carol-peixinho-curte-praia-no-porto-da-barra-depois-de-correr-5-km-domingo-16-04-2023-17h00-por-redacao-carol-peixinho-curte-praia-no-porto-da-barra-depois-de-correr-5-km-f","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2023\/04\/16\/ver-todas-de-colunistas-carol-peixinho-curte-praia-no-porto-da-barra-depois-de-correr-5-km-domingo-16-04-2023-17h00-por-redacao-carol-peixinho-curte-praia-no-porto-da-barra-depois-de-correr-5-km-f\/","title":{"rendered":"Cach\u00eas de L\u00e9o Santana e Saia Rodada em festa na Bahia s\u00e3o contestados pelo Tribunal de Contas"},"content":{"rendered":"<div id=\"attachment_26306\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-26306\" loading=\"lazy\" class=\"wp-image-26306 size-medium\" src=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2023\/04\/IMAGEM_NOTICIA_5-_3_-300x191.jpg\" alt=\"\" width=\"300\" height=\"191\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2023\/04\/IMAGEM_NOTICIA_5-_3_-300x191.jpg 300w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2023\/04\/IMAGEM_NOTICIA_5-_3_.jpg 597w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-26306\" class=\"wp-caption-text\">Foto: Reprodu\u00e7\u00e3o\/Redes Sociais<\/p><\/div>\n<h3 style=\"font-weight: 400; text-align: justify;\">O Tribunal de Contas dos Munic\u00edpios da Bahia (TCM) determinou, nesta quinta-feira (13), que a Prefeitura de Jaborandi suspenda os shows que\u00a0<a href=\"https:\/\/www.bahianoticias.com.br\/tags\/leo-santana\">L\u00e9o Santana<\/a>\u00a0e Saia Rodada far\u00e3o para a 25\u00aa Festa de Santo Ant\u00f4nio no munic\u00edpio. A decis\u00e3o liminar foi expedida pelo conselheiro Fernando Vita e deve ser apreciada pelos demais integrantes da Corte.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">L\u00e9o Santana foi contratado no valor de R$ 350 mil e a banda Saia Rodada no valor de R$ 380 mil,\u00a0totalizando R$ 730 mil na contrata\u00e7\u00e3o dos dois artistas.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">O TCM afirma que os artistas foram contratados por valores superiores aos cobrados pelos mesmos artistas em outras cidades. E que o valor representa quase 14% da Arrecada\u00e7\u00e3o Mensal Corrente do munic\u00edpio.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">\u201cIsto \u00e9, de forma desarrazoada, antiecon\u00f4mica, desproporcional, ferindo a moralidade administrativa, uma vez que o munic\u00edpio possui popula\u00e7\u00e3o estimada, conforme IBGE (2021), de SOMENTE 8.176\u00a0 habitantes e sua Receita Corrente Mensal \u00e9 de aproximadamente R$ 5,3 milh\u00f5es de reais, conforme Demonstrativo Consolidado da Receita Or\u00e7ament\u00e1ria de 2021 (Arrecada\u00e7\u00e3o Total no SIGA de R$ 64.362.501,08), representando esse gasto quase 14% da sua Arrecada\u00e7\u00e3o Mensal Corrente\u201d, diz o TCM.<\/h3>\n<h3 style=\"font-weight: 400; text-align: justify;\">Em contato com o Bahia Not\u00edcias, a equipe de L\u00e9o Santana informou que o show n\u00e3o foi cancelado e que os novos documentos solicitados pelo TCM ser\u00e3o enviados.<\/h3>\n<h3 style=\"text-align: justify;\">Bahia Not\u00edcias<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Contas dos Munic\u00edpios da Bahia (TCM) determinou, nesta quinta-feira (13), que a Prefeitura de Jaborandi suspenda os shows que\u00a0L\u00e9o Santana\u00a0e Saia Rodada far\u00e3o para a 25\u00aa Festa de Santo Ant\u00f4nio no munic\u00edpio. A decis\u00e3o liminar foi expedida pelo conselheiro Fernando Vita e deve ser apreciada pelos demais integrantes da Corte. L\u00e9o Santana [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/26305"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=26305"}],"version-history":[{"count":3,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/26305\/revisions"}],"predecessor-version":[{"id":26309,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/26305\/revisions\/26309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/26306"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=26305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=26305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=26305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}