{"id":3061,"date":"2017-03-16T07:48:00","date_gmt":"2017-03-16T10:48:00","guid":{"rendered":"http:\/\/www.cidadeemnoticias.com.br\/v1\/?p=3061"},"modified":"2017-03-16T07:48:00","modified_gmt":"2017-03-16T10:48:00","slug":"itiuba-aplb-sindicado-adere-a-paralisacao-nacional","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2017\/03\/16\/itiuba-aplb-sindicado-adere-a-paralisacao-nacional\/","title":{"rendered":"ITI\u00daBA: APLB SINDICADO ADERE A PARALISA\u00c7\u00c3O NACIONAL"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-1541 aligncenter\" src=\"http:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/01\/APLB-300x173.jpg\" alt=\"aplb\" width=\"496\" height=\"286\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/01\/APLB-300x173.jpg 300w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/01\/APLB.jpg 400w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/><\/p>\n<h3 style=\"text-align: justify;\">O Sindicato dos Trabalhadores em Educa\u00e7\u00e3o do Estado da Bahia (APLB), em reuni\u00e3o no \u00faltimo s\u00e1bado (11\/03\/2017), determinou a ades\u00e3o ao movimento de greve\u00a0nacional que ocorre em todo o Brasil de 15 a 24 de mar\u00e7o.<\/h3>\n<p><img loading=\"lazy\" class=\" wp-image-3084 aligncenter\" src=\"http:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/03\/17190398_647982798720499_3230263643681952425_n-221x300.jpg\" alt=\"17190398_647982798720499_3230263643681952425_n\" width=\"450\" height=\"611\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/03\/17190398_647982798720499_3230263643681952425_n-221x300.jpg 221w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/03\/17190398_647982798720499_3230263643681952425_n.jpg 540w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Em entrevista ao Jornal Cidade em Not\u00edcias, a Presidente da APLB de Iti\u00faba, Dr\u00aa Cicleide Madureira falou da import\u00e2ncia da paralisa\u00e7\u00e3o\u00a0nacional como forma de reivindica\u00e7\u00e3o dos direitos dos trabalhadores que ser\u00e1 ceifados caso a reforma da previd\u00eancia seja aprovada.<\/h3>\n<p>Cidade em Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sindicato dos Trabalhadores em Educa\u00e7\u00e3o do Estado da Bahia (APLB), em reuni\u00e3o no \u00faltimo s\u00e1bado (11\/03\/2017), determinou a ades\u00e3o ao movimento de greve\u00a0nacional que ocorre em todo o Brasil de 15 a 24 de mar\u00e7o. Em entrevista ao Jornal Cidade em Not\u00edcias, a Presidente da APLB de Iti\u00faba, Dr\u00aa Cicleide Madureira falou da import\u00e2ncia [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[2,1,26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3061"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=3061"}],"version-history":[{"count":2,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3061\/revisions"}],"predecessor-version":[{"id":3085,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3061\/revisions\/3085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/3051"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=3061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=3061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=3061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}