{"id":3377,"date":"2017-04-09T16:26:37","date_gmt":"2017-04-09T19:26:37","guid":{"rendered":"http:\/\/www.cidadeemnoticias.com.br\/v1\/?p=3377"},"modified":"2017-04-09T16:26:37","modified_gmt":"2017-04-09T19:26:37","slug":"secretaria-de-acao-social-realiza-a-primeira-jornada-social-para-orientadores-e-oficineiros-do-servico-de-convivencia-e-fortalecimento-de-vinculos-scfv","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2017\/04\/09\/secretaria-de-acao-social-realiza-a-primeira-jornada-social-para-orientadores-e-oficineiros-do-servico-de-convivencia-e-fortalecimento-de-vinculos-scfv\/","title":{"rendered":"SECRETARIA DE A\u00c7\u00c3O SOCIAL REALIZA A PRIMEIRA JORNADA SOCIAL PARA ORIENTADORES E OFICINEIROS DO SERVI\u00c7O DE CONVIV\u00caNCIA E FORTALECIMENTO DE VINCULOS \u2013 SCFV"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-3378 aligncenter\" src=\"http:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/04\/17799364_445072129169266_8305351874670177457_n-300x174.jpg\" alt=\"17799364_445072129169266_8305351874670177457_n\" width=\"544\" height=\"315\" srcset=\"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/04\/17799364_445072129169266_8305351874670177457_n-300x174.jpg 300w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/04\/17799364_445072129169266_8305351874670177457_n-768x446.jpg 768w, https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-content\/uploads\/2017\/04\/17799364_445072129169266_8305351874670177457_n.jpg 960w\" sizes=\"(max-width: 544px) 100vw, 544px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Nesses dois dias de capacita\u00e7\u00e3o cerca de 110 trabalhadores estar\u00e3o voltados para o aprimoramento de suas habilidades.<\/h3>\n<h3 style=\"text-align: justify;\">A Prefeita Municipal de Iti\u00faba Cec\u00edlia Petrina de Carvalho, atrav\u00e9s da Secretaria Municipal de A\u00e7\u00e3o Social e sua representante legal Rosineide Barbosa Dias, promoveu nesta manh\u00e3 de quinta-feira (06) a I Jornada Social para Orientadores e Oficineiros do Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos.<\/h3>\n<h3 style=\"text-align: justify;\">O evento aconteceu na sede do SCFV Idoso, localizado no Centro S\u00e3o Vicente de Paula, e foi direcionado especialmente aos Orientadores e Oficineiros sociais que estar\u00e3o executando os servi\u00e7os socioeducativos nucleados na sede do munic\u00edpio e zona rural, estendendo-se at\u00e9 a sexta-feira, dia 07 de abril.<\/h3>\n<h3 style=\"text-align: justify;\">O SCFV atende no munic\u00edpio de Iti\u00faba cerca de 840 usu\u00e1rios dos servi\u00e7os assistenciais, sendo 50% dessas inser\u00e7\u00f5es direcionadas para o p\u00fablico priorit\u00e1rio: crian\u00e7as em situa\u00e7\u00e3o de explora\u00e7\u00e3o do trabalho infantil, adolescentes e idosos v\u00edtimas de viol\u00eancia, neglig\u00eancia, discrimina\u00e7\u00e3o, explora\u00e7\u00e3o e abuso, al\u00e9m de outros grupos vulner\u00e1veis.<\/h3>\n<h3 style=\"text-align: justify;\">A Prefeita Cec\u00edlia e a Secret\u00e1ria de A\u00e7\u00e3o Social Rosineide Dias acreditam que a educa\u00e7\u00e3o permanente potencializa as habilidades dos trabalhadores do Sistema \u00danico de Assist\u00eancia Social &#8211; SUAS, o que resulta em qualifica\u00e7\u00e3o dos servi\u00e7os, atendimentos e acompanhamentos aos usu\u00e1rios da assist\u00eancia social.<\/h3>\n<h3 style=\"text-align: justify;\">Nesses dois dias de capacita\u00e7\u00e3o cerca de 110 trabalhadores estar\u00e3o voltados para o aprimoramento de suas habilidades. \u00c9 a Assist\u00eancia Social em desenvolvimento, trabalho e compet\u00eancia!<\/h3>\n<p>ASCOM &#8211; PMI<br \/>\nGOVERNO DESENVOLVIMENTO, COMPET\u00caNCIA E TRABALHO<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesses dois dias de capacita\u00e7\u00e3o cerca de 110 trabalhadores estar\u00e3o voltados para o aprimoramento de suas habilidades. A Prefeita Municipal de Iti\u00faba Cec\u00edlia Petrina de Carvalho, atrav\u00e9s da Secretaria Municipal de A\u00e7\u00e3o Social e sua representante legal Rosineide Barbosa Dias, promoveu nesta manh\u00e3 de quinta-feira (06) a I Jornada Social para Orientadores e Oficineiros do [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1,26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3377"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=3377"}],"version-history":[{"count":1,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3377\/revisions"}],"predecessor-version":[{"id":3379,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3377\/revisions\/3379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=3377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=3377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=3377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}