{"id":3717,"date":"2017-05-09T09:27:46","date_gmt":"2017-05-09T12:27:46","guid":{"rendered":"http:\/\/www.cidadeemnoticias.com.br\/v1\/?p=3717"},"modified":"2017-05-13T08:35:05","modified_gmt":"2017-05-13T11:35:05","slug":"cpac-apreende-arma-e-drogas-proximo-a-itiuba","status":"publish","type":"post","link":"https:\/\/www.cidadeemnoticias.com.br\/v1\/2017\/05\/09\/cpac-apreende-arma-e-drogas-proximo-a-itiuba\/","title":{"rendered":"CPAC apreende arma e drogas pr\u00f3ximo a Iti\u00faba"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"aligncenter wp-image-38955\" src=\"http:\/\/blogdonettomaravilha.com.br\/wp-content\/uploads\/2017\/03\/logo-cpac-210x158.jpg\" sizes=\"(max-width: 350px) 100vw, 350px\" srcset=\"http:\/\/blogdonettomaravilha.com.br\/wp-content\/uploads\/2017\/03\/logo-cpac-200x150.jpg 200w, http:\/\/blogdonettomaravilha.com.br\/wp-content\/uploads\/2017\/03\/logo-cpac-210x158.jpg 210w, http:\/\/blogdonettomaravilha.com.br\/wp-content\/uploads\/2017\/03\/logo-cpac-400x300.jpg 400w, http:\/\/blogdonettomaravilha.com.br\/wp-content\/uploads\/2017\/03\/logo-cpac-600x450.jpg 600w, http:\/\/blogdonettomaravilha.com.br\/wp-content\/uploads\/2017\/03\/logo-cpac.jpg 650w\" alt=\"\" width=\"350\" height=\"263\" \/><\/p>\n<h3 style=\"text-align: justify;\">Por volta das 22h30min desse domingo (07), a Guarni\u00e7\u00e3o CPAC apreendeu uma arma de fogo de fabrica\u00e7\u00e3o caseira com tr\u00eas frascos contendo p\u00f3lvora, chumbo e espoleta, al\u00e9m de 16 pedras de crack, 08 dol\u00f5es de maconha e 12 g de coca\u00edna, fato corrido durante abordagem na Rua do Beco sem Sa\u00edda, Loteamento Sertanejo em Iti\u00faba. Os autores evadiram-se por um terreno nos fundos da casa, impossibilitando a pris\u00e3o, por\u00e9m a PM j\u00e1 tem a identifica\u00e7\u00e3o dos mesmos.<\/h3>\n<h3 style=\"text-align: justify;\">O material apreendido foi apresentado na DT\/Bonfim.<\/h3>\n<p>Blog do Netto Maravilha<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 22h30min desse domingo (07), a Guarni\u00e7\u00e3o CPAC apreendeu uma arma de fogo de fabrica\u00e7\u00e3o caseira com tr\u00eas frascos contendo p\u00f3lvora, chumbo e espoleta, al\u00e9m de 16 pedras de crack, 08 dol\u00f5es de maconha e 12 g de coca\u00edna, fato corrido durante abordagem na Rua do Beco sem Sa\u00edda, Loteamento Sertanejo em Iti\u00faba. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[4,1,26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3717"}],"collection":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/comments?post=3717"}],"version-history":[{"count":1,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3717\/revisions"}],"predecessor-version":[{"id":3719,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/posts\/3717\/revisions\/3719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media\/3718"}],"wp:attachment":[{"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/media?parent=3717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/categories?post=3717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidadeemnoticias.com.br\/v1\/wp-json\/wp\/v2\/tags?post=3717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}